{"id":24300,"date":"2021-02-25T18:45:04","date_gmt":"2021-02-25T17:45:04","guid":{"rendered":"http:\/\/www.lemonskin.net\/io\/?p=24300"},"modified":"2026-07-09T13:02:34","modified_gmt":"2026-07-09T11:02:34","slug":"le-mappe-dello-hobbit","status":"publish","type":"post","link":"https:\/\/www.lemonskin.net\/io\/24300\/","title":{"rendered":"Le mappe dello Hobbit"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"434\" src=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-01.jpg\" alt=\"\" class=\"wp-image-24301\" srcset=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-01.jpg 730w, https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-01-300x178.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/figure>\n\n\n\n<details class=\"wp-block-details info is-layout-flow wp-block-details-is-layout-flow\"><summary>Doverosa premessa<\/summary>\n<p>Non ho (ri)disegnato queste mappe, sono 100% opera di Christopher Tolkien.<\/p>\n\n\n\n<p>Ma andiamo con ordine&#8230;<\/p>\n<\/details>\n\n\n\n<p class=\"has-drop-cap\">A differenza della travagliata storia delle mappe del <em>Signore degli Anelli<\/em> (solo quest&#8217;anno Bompiani \u00e8 riuscita a includerle tutte e tre nel suo nuovo volume unico, bench\u00e9 molto, molto, molto brutte), lo <em>Hobbit<\/em> le ha sempre avute tutte, gi\u00e0 tradotte sin dalla prima edizione.<\/p>\n\n\n\n<p>Siccome ne avevo bisogno per un progetto <s>di cui vi parler\u00f2 tra circa un mesetto, perch\u00e9 per il momento \u00e8 <em>super top secret<\/em><\/s> (ora posso svelarlo, <a rel=\"noreferrer noopener\" href=\"https:\/\/www.lemonskin.net\/io\/24250\/\" data-type=\"post\" data-id=\"24250\" target=\"_blank\">\u00e8 questo<\/a>), e mi servivano originali, ho cominciato a scartabellare tutte le mie edizioni italiane per trovare quelle stampate meglio.<\/p>\n\n\n\n<p>E, indovina un po&#8217;? Le migliori in assoluto sono quelle allegate alla <a rel=\"noreferrer noopener\" href=\"https:\/\/www.lemonskin.net\/io\/19456\/\" data-type=\"post\" data-id=\"19456\" target=\"_blank\">prima edizione italiana<\/a> pubblicata da Adelphi! S\u00ec lo so, \u00e8 ridicolo: dover prendere un libro di mezzo secolo fa perch\u00e9 Bompiani non si \u00e8 mai sbattuta per inserire mappe qualitativamente decenti nelle proprie edizioni.<\/p>\n\n\n\n<p>E non sto parlando di piccoli dettagli visibili solo con la lente&#8230;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"495\" src=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-02.jpg\" alt=\"\" class=\"wp-image-24304\" srcset=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-02.jpg 730w, https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-02-300x203.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/figure>\n\n\n\n<p>Per capirci, quella sopra \u00e8 la mappa dell&#8217;attuale edizione Deluxe Bompiani rilegata, la versione pi\u00f9 lussuosa esistente, attualmente in vendita a ben 30 euro. Quella sotto \u00e8 la prima edizione italiana del 1973.<\/p>\n\n\n\n<!--more-->\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"377\" src=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-03.jpg\" alt=\"\" class=\"wp-image-24305\" srcset=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-03.jpg 730w, https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-03-300x155.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/figure>\n\n\n\n<p>Guardando pi\u00f9 in dettaglio, questa volta con la Deluxe a sinistra, \u00e8 chiaro di che razza di porcheria stiamo parlando: le scritte nemmeno si leggono. Non so se questo dipenda da una scansione fatta coi piedi o da una riproduzione effettuata dal figlio del nipote del cugino per 10 euro; il risultato \u00e8 vergognoso.<\/p>\n\n\n\n<p>Sorvolo sul fatto che all&#8217;editore non sia mai passata per l&#8217;anticamera del cervello l&#8217;idea che stampare una mappa su due fogli comporta automaticamente la perdita della parte centrale, che finisce per affogare all&#8217;interno della rilegatura (nota la ragnatela centrale nella prima immagine di comparazione). Infatti, le mappe di Adelphi si trovano su pagine ripiegate (almeno fino al 1982 o gi\u00f9 di l\u00ec, quando anche quell&#8217;editore ha optato per una stampa pi\u00f9 al risparmio)<\/p>\n\n\n\n<p>Nessun&#8217;altra edizione italiana in mio possesso (sette in totale) aveva mappe lontanamente paragonabili a quelle del &#8217;73, pertanto mi sono armato di pazienza e (molto) coraggio, e ho tirato fuori il mio <em>tesssoro<\/em> dalla libreria.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"506\" src=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-04.jpg\" alt=\"\" class=\"wp-image-24306\" srcset=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-04.jpg 730w, https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-04-300x208.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/figure>\n\n\n\n<p>Il primo pensiero \u00e8 stato di infilarlo dentro lo scanner. Tale operazione, per\u00f2, richiedeva che appiattissi il libro a 180\u00b0, operazione che non mi sono sentito di fare con un prezioso libro di quasi 50 anni fa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"548\" src=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-05.jpg\" alt=\"\" class=\"wp-image-24307\" srcset=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-05.jpg 730w, https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-05-300x225.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/figure>\n\n\n\n<p>Ho pertanto optato per un approccio ibrido. Ho inserito il libro all&#8217;interno dello scanner fin quando ho potuto, evitando di incrementare l&#8217;angolo di apertura della pagina oltre i 90\u00b0.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"462\" src=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-07.jpg\" alt=\"\" class=\"wp-image-24308\" srcset=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-07.jpg 730w, https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-07-300x190.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/figure>\n\n\n\n<p>Con questo schizzetto a mano forse si riesce a comprendere meglio l&#8217;operazione. In questo modo non sono stato in grado di scansionare pi\u00f9 del 70% delle mappe. Per la parte restante ho fatto quante pi\u00f9 foto particolareggiate possibili col mio vecchissimo, ma pur sempre onorevole, iPhone 6.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"583\" src=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-06.jpg\" alt=\"\" class=\"wp-image-24309\" srcset=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-06.jpg 730w, https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-06-300x240.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/figure>\n\n\n\n<p>A quel punto ho cominciato a mettere insieme un collage piuttosto disomogeneo di sorgenti grafiche. Ti risparmio il lungo lavoro di correzione delle distorsioni e della prospettiva, dei contrasti, del colore, delle proporzioni e delle dimensioni su entrambe le mappe. Ho anche dovuto estrapolare i due colori base, il nero e il rosso, ed elaborarli singolarmente su livelli differenti (\u00e8 un discorso complicato ma, a un certo punto, anche tutto ci\u00f2 che \u00e8 rosso \u00e8 diventato nero, per poi tornare a essere nuovamente rosso).<\/p>\n\n\n\n<p>Le ho infine fatte stampare su carta 120g tramite tecnologia laser dalla mia tipografia di fiducia e come risultato mi sono ritrovato tra le mani quelle che molto, <em>molto<\/em>, <span style=\"text-decoration: underline;\">molto<\/span>, MOLTO immodestamente considero le migliori riproduzioni delle mappe italiane dello Hobbit:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"516\" src=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-08.jpg\" alt=\"\" class=\"wp-image-24310\" srcset=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-08.jpg 730w, https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-08-300x212.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><figcaption class=\"wp-element-caption\">La Mappa di Thr\u00f3r<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"492\" src=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-09.jpg\" alt=\"\" class=\"wp-image-24311\" srcset=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-09.jpg 730w, https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-09-300x202.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><figcaption class=\"wp-element-caption\">La Mappa delle Terre Selvagge<\/figcaption><\/figure>\n\n\n\n<p>Chiudo l&#8217;articolo con qualche vista pi\u00f9 dettagliata:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"421\" src=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-10.jpg\" alt=\"\" class=\"wp-image-24312\" srcset=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-10.jpg 730w, https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-10-300x173.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"503\" src=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-11.jpg\" alt=\"\" class=\"wp-image-24313\" srcset=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-11.jpg 730w, https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-11-300x207.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"548\" src=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-12.jpg\" alt=\"\" class=\"wp-image-24314\" srcset=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-12.jpg 730w, https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-12-300x225.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"455\" src=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-13.jpg\" alt=\"\" class=\"wp-image-24315\" srcset=\"https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-13.jpg 730w, https:\/\/www.lemonskin.net\/io\/wp-content\/uploads\/2021\/02\/Mappe-Hobbit-13-300x187.jpg 300w\" sizes=\"auto, (max-width: 730px) 100vw, 730px\" \/><\/figure>\n\n\n\n<details class=\"wp-block-details info is-layout-flow wp-block-details-is-layout-flow\"><summary>Nota<\/summary>\n<p>Parte della nomenclatura suona un po&#8217; strana, tipo <em>Smog<\/em> (sappiamo tutti che il nome corretto \u00e8 Smaug) o Forraspaccata, perch\u00e9 mi sono rigorosamente attenuto alle mappe originali, che si riferiscono alla prima traduzione italiana a cura di Elena Jeronimidis Conte.<\/p>\n<\/details>\n\n\n\n<details class=\"wp-block-details importante is-layout-flow wp-block-details-is-layout-flow\"><summary>Codici di riferimento<\/summary>\n<p>Se hai bisogno di maggiori informazioni su una specifica variante di questa mappa, comunicami il codice in verde che trovi qui sotto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mappa di Thr\u00f3r<\/h2>\n\n\n\n<div class=\"wp-block-getwid-table\"><table><thead><tr><th style=\"text-align:center;background-color:#f5f5f5;color:#9b9b9b\">Nome<\/th><th style=\"background-color:#f5f5f5;color:#9b9b9b;text-align:center\">Dimensioni<\/th><th style=\"text-align:center;background-color:#f5f5f5;color:#9b9b9b\">Nomenclatura<\/th><th style=\"text-align:center;background-color:#f5f5f5;color:#9b9b9b\">Codice<\/th><\/tr><\/thead><tbody><tr><td rowspan=\"3\" style=\"text-align:center;color:#ff6900\"><strong>Thr\u00f3r<\/strong><\/td><td style=\"text-align:center\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#8048c9\" class=\"has-inline-color\">80 x 60 cm<\/mark><\/td><td rowspan=\"3\" style=\"color:#fcb900;text-align:center\">Hobbit<\/td><td><span onclick=\"CopiaClip(this)\" class=\"bottone_codice\" title=\"Clicca per copiare nella clipboard.\">B-H1<\/span><\/td><\/tr><tr><td rowspan=\"1\" style=\"text-align:center\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#ca51e0\" class=\"has-inline-color\">50 x 35 cm<\/mark><\/td><td style=\"text-align:left\"><span onclick=\"CopiaClip(this)\" class=\"bottone_codice\" title=\"Clicca per copiare nella clipboard.\">M-H1<\/span><\/td><\/tr><tr><td style=\"text-align:center;color:#e051b3\">A4<\/td><td><span onclick=\"CopiaClip(this)\" class=\"bottone_codice\" title=\"Clicca per copiare nella clipboard.\">S-H1<\/span><\/td><\/tr><\/tbody><\/table><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Mappa delle Terre Selvagge<\/h2>\n\n\n\n<div class=\"wp-block-getwid-table\"><table><thead><tr><th style=\"text-align:center;background-color:#f5f5f5;color:#9b9b9b\">Nome<\/th><th style=\"background-color:#f5f5f5;color:#9b9b9b;text-align:center\">Dimensioni<\/th><th style=\"text-align:center;background-color:#f5f5f5;color:#9b9b9b\">Nomenclatura<\/th><th style=\"text-align:center;background-color:#f5f5f5;color:#9b9b9b\">Codice<\/th><\/tr><\/thead><tbody><tr><td rowspan=\"3\" style=\"text-align:center;color:#ff6900\"><strong>Terre Selvagge<\/strong><\/td><td style=\"text-align:center\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#8048c9\" class=\"has-inline-color\">80 x 60 cm<\/mark><\/td><td rowspan=\"3\" style=\"color:#fcb900;text-align:center\">Hobbit<\/td><td><span onclick=\"CopiaClip(this)\" class=\"bottone_codice\" title=\"Clicca per copiare nella clipboard.\">B-H2<\/span><\/td><\/tr><tr><td rowspan=\"1\" style=\"text-align:center\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#ca51e0\" class=\"has-inline-color\">50 x 35 cm<\/mark><\/td><td style=\"text-align:left\"><span onclick=\"CopiaClip(this)\" class=\"bottone_codice\" title=\"Clicca per copiare nella clipboard.\">M-H2<\/span><\/td><\/tr><tr><td style=\"text-align:center;color:#e051b3\">A4<\/td><td><span onclick=\"CopiaClip(this)\" class=\"bottone_codice\" title=\"Clicca per copiare nella clipboard.\">S-H2<\/span><\/td><\/tr><\/tbody><\/table><\/div>\n<\/details>\n\n\n\n<p>Se vuoi saperne di pi\u00f9 su queste mappe, puoi&nbsp;<a href=\"https:\/\/www.lemonskin.net\/io\/21799\/#contattami\" target=\"_blank\" rel=\"noreferrer noopener\">contattarmi qui<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A differenza della travagliata storia delle mappe del Signore degli Anelli (solo quest&#8217;anno Bompiani \u00e8 riuscita a includerle tutte e tre nel suo nuovo volume unico, bench\u00e9 molto, molto, molto brutte), lo Hobbit le ha sempre avute tutte, gi\u00e0 tradotte sin dalla prima edizione. Siccome ne avevo bisogno per un progetto di cui vi parler\u00f2&hellip; <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_stopmodifiedupdate":false,"_modified_date":"","advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[38,9],"tags":[111259,111314,111204,111176,111203,111202,111362,111248,111258],"class_list":["post-24300","post","type-post","status-publish","format-standard","hentry","category-arte","category-libri","tag-amm","tag-elaborazioni","tag-il-signore-degli-anelli","tag-immagini","tag-tolkien","tag-hobbit","tag-lrx","tag-mappe","tag-photoshop"],"acf":[],"author_meta":{"display_name":"lock","author_link":"https:\/\/www.lemonskin.net\/io\/author\/lock\/"},"featured_img":null,"jetpack_featured_media_url":"","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.lemonskin.net\/io\/category\/arte\/\" class=\"advgb-post-tax-term\">arte<\/a>","<a href=\"https:\/\/www.lemonskin.net\/io\/category\/libri\/\" class=\"advgb-post-tax-term\">libri<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">arte<\/span>","<span class=\"advgb-post-tax-term\">libri<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/www.lemonskin.net\/io\/category\/libri\/\" class=\"advgb-post-tax-term\">AMM<\/a>","<a href=\"https:\/\/www.lemonskin.net\/io\/category\/libri\/\" class=\"advgb-post-tax-term\">elaborazioni<\/a>","<a href=\"https:\/\/www.lemonskin.net\/io\/category\/libri\/\" class=\"advgb-post-tax-term\">il Signore degli Anelli<\/a>","<a href=\"https:\/\/www.lemonskin.net\/io\/category\/libri\/\" class=\"advgb-post-tax-term\">immagini<\/a>","<a href=\"https:\/\/www.lemonskin.net\/io\/category\/libri\/\" class=\"advgb-post-tax-term\">J.R.R. Tolkien<\/a>","<a href=\"https:\/\/www.lemonskin.net\/io\/category\/libri\/\" class=\"advgb-post-tax-term\">lo Hobbit<\/a>","<a href=\"https:\/\/www.lemonskin.net\/io\/category\/libri\/\" class=\"advgb-post-tax-term\">lrx<\/a>","<a href=\"https:\/\/www.lemonskin.net\/io\/category\/libri\/\" class=\"advgb-post-tax-term\">mappe<\/a>","<a href=\"https:\/\/www.lemonskin.net\/io\/category\/libri\/\" class=\"advgb-post-tax-term\">Photoshop<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">AMM<\/span>","<span class=\"advgb-post-tax-term\">elaborazioni<\/span>","<span class=\"advgb-post-tax-term\">il Signore degli Anelli<\/span>","<span class=\"advgb-post-tax-term\">immagini<\/span>","<span class=\"advgb-post-tax-term\">J.R.R. Tolkien<\/span>","<span class=\"advgb-post-tax-term\">lo Hobbit<\/span>","<span class=\"advgb-post-tax-term\">lrx<\/span>","<span class=\"advgb-post-tax-term\">mappe<\/span>","<span class=\"advgb-post-tax-term\">Photoshop<\/span>"]}},"comment_count":"4","relative_dates":{"created":"Pubblicato 5 anni fa","modified":"Aggiornato 6 giorni fa"},"absolute_dates":{"created":"Pubblicato il 25 Febbraio 2021","modified":"Aggiornato il 9 Luglio 2026"},"absolute_dates_time":{"created":"Pubblicato il 25 Febbraio 2021 18:45","modified":"Aggiornato il 9 Luglio 2026 13:02"},"featured_img_caption":"","series_order":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lemonskin.net\/io\/wp-json\/wp\/v2\/posts\/24300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lemonskin.net\/io\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lemonskin.net\/io\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lemonskin.net\/io\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lemonskin.net\/io\/wp-json\/wp\/v2\/comments?post=24300"}],"version-history":[{"count":4,"href":"https:\/\/www.lemonskin.net\/io\/wp-json\/wp\/v2\/posts\/24300\/revisions"}],"predecessor-version":[{"id":52527,"href":"https:\/\/www.lemonskin.net\/io\/wp-json\/wp\/v2\/posts\/24300\/revisions\/52527"}],"wp:attachment":[{"href":"https:\/\/www.lemonskin.net\/io\/wp-json\/wp\/v2\/media?parent=24300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lemonskin.net\/io\/wp-json\/wp\/v2\/categories?post=24300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lemonskin.net\/io\/wp-json\/wp\/v2\/tags?post=24300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}